{"id":1078,"date":"2023-11-24T14:24:04","date_gmt":"2023-11-24T13:24:04","guid":{"rendered":"https:\/\/dev-binvex.pantheonsite.io\/?page_id=1078"},"modified":"2023-11-24T14:36:10","modified_gmt":"2023-11-24T13:36:10","slug":"vautid-odlivci-otporni-na-abraziju","status":"publish","type":"page","link":"https:\/\/binvex.com\/en\/vautid-odlivci-otporni-na-abraziju\/","title":{"rendered":"Vautid odlivci otporni na abraziju"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1078\" class=\"elementor elementor-1078\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd32e6e e-flex e-con-boxed e-con e-parent\" data-id=\"fd32e6e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be9b77f elementor-widget elementor-widget-heading\" data-id=\"be9b77f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VAUTID ODLIVCI OTPORNI NA ABRAZIJU<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73f1306 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"73f1306\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-58ee3d3 e-flex e-con-boxed e-con e-parent\" data-id=\"58ee3d3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-80ebead elementor-posts--align-center elementor-grid-tablet-1 elementor-grid-3 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"80ebead\" data-element_type=\"widget\" data-settings=\"{&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;classic_columns_tablet&quot;:&quot;1&quot;,&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1080 post type-post status-publish format-standard has-post-thumbnail hentry category-vautid-odlivci-otporni-na-abraziju\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/binvex.com\/en\/odlivci-protiv-habanja-vautid-w78a\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w78A.jpg\" class=\"attachment-full size-full wp-image-1081\" alt=\"\" srcset=\"https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w78A.jpg 600w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w78A-300x300.jpg 300w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w78A-150x150.jpg 150w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w78A-12x12.jpg 12w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w78A-100x100.jpg 100w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/binvex.com\/en\/odlivci-protiv-habanja-vautid-w78a\/\" >\n\t\t\t\tOdlivci protiv habanja \u2013 VAUTID W78A\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1084 post type-post status-publish format-standard has-post-thumbnail hentry category-vautid-odlivci-otporni-na-abraziju\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/binvex.com\/en\/odlivci-protiv-habanja-vautid-w73\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w73.jpg\" class=\"attachment-full size-full wp-image-1085\" alt=\"\" srcset=\"https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w73.jpg 600w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w73-300x300.jpg 300w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w73-150x150.jpg 150w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w73-12x12.jpg 12w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w73-100x100.jpg 100w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/binvex.com\/en\/odlivci-protiv-habanja-vautid-w73\/\" >\n\t\t\t\tOdlivci protiv habanja \u2013 VAUTID W73\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1087 post type-post status-publish format-standard has-post-thumbnail hentry category-vautid-odlivci-otporni-na-abraziju\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/binvex.com\/en\/odlivci-protiv-habanja-vautid-w72\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w72.jpg\" class=\"attachment-full size-full wp-image-1088\" alt=\"\" srcset=\"https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w72.jpg 600w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w72-300x300.jpg 300w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w72-150x150.jpg 150w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w72-12x12.jpg 12w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w72-100x100.jpg 100w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/binvex.com\/en\/odlivci-protiv-habanja-vautid-w72\/\" >\n\t\t\t\tOdlivci protiv habanja \u2013 VAUTID W72\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1090 post type-post status-publish format-standard has-post-thumbnail hentry category-vautid-odlivci-otporni-na-abraziju\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/binvex.com\/en\/odlivci-protiv-habanja-vautid-w7\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w7.jpg\" class=\"attachment-full size-full wp-image-1091\" alt=\"\" srcset=\"https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w7.jpg 600w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w7-300x300.jpg 300w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w7-150x150.jpg 150w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w7-12x12.jpg 12w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w7-100x100.jpg 100w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/binvex.com\/en\/odlivci-protiv-habanja-vautid-w7\/\" >\n\t\t\t\tOdlivci protiv habanja \u2013 VAUTID W7\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1093 post type-post status-publish format-standard has-post-thumbnail hentry category-vautid-odlivci-otporni-na-abraziju\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/binvex.com\/en\/odlivci-protiv-habanja-vautid-w4\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w4.jpg\" class=\"attachment-full size-full wp-image-1094\" alt=\"\" srcset=\"https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w4.jpg 600w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w4-300x300.jpg 300w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w4-150x150.jpg 150w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w4-12x12.jpg 12w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w4-100x100.jpg 100w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/binvex.com\/en\/odlivci-protiv-habanja-vautid-w4\/\" >\n\t\t\t\tOdlivci protiv habanja \u2013 VAUTID W4\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1096 post type-post status-publish format-standard has-post-thumbnail hentry category-vautid-odlivci-otporni-na-abraziju\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/binvex.com\/en\/odlivci-protiv-habanja-vautid-w3\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w3.jpg\" class=\"attachment-full size-full wp-image-1097\" alt=\"\" srcset=\"https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w3.jpg 600w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w3-300x300.jpg 300w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w3-150x150.jpg 150w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w3-12x12.jpg 12w, https:\/\/binvex.com\/wp-content\/uploads\/2023\/11\/naslovna-slika-vautid-w3-100x100.jpg 100w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/binvex.com\/en\/odlivci-protiv-habanja-vautid-w3\/\" >\n\t\t\t\tOdlivci protiv habanja \u2013 VAUTID W3\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>VAUTID ODLIVCI OTPORNI NA ABRAZIJU<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_eb_attr":"","footnotes":""},"class_list":["post-1078","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/binvex.com\/en\/wp-json\/wp\/v2\/pages\/1078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/binvex.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/binvex.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/binvex.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/binvex.com\/en\/wp-json\/wp\/v2\/comments?post=1078"}],"version-history":[{"count":0,"href":"https:\/\/binvex.com\/en\/wp-json\/wp\/v2\/pages\/1078\/revisions"}],"wp:attachment":[{"href":"https:\/\/binvex.com\/en\/wp-json\/wp\/v2\/media?parent=1078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}